{"id":3829,"date":"2022-01-31T19:13:48","date_gmt":"2022-01-31T19:13:48","guid":{"rendered":"https:\/\/eczemahelp.ca\/blog\/un-medecin-vous-parle-de-phototherapie\/"},"modified":"2024-12-19T21:23:30","modified_gmt":"2024-12-19T21:23:30","slug":"un-medecin-vous-parle-de-phototherapie","status":"publish","type":"post","link":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/","title":{"rendered":"Un m\u00e9decin vous parle&#8230; de phototh\u00e9rapie"},"content":{"rendered":"<h1>Phototh\u00e9rapie contre l\u2019ecz\u00e9ma : comment \u00e7a consiste?<\/h1>\n<p>Qu\u2019est-ce que la phototh\u00e9rapie, et comment peut-elle aider les personnes atteintes d\u2019ecz\u00e9ma? Est-ce un peu comme de passer du temps au soleil?\u00a0La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma a demand\u00e9 au D<sup>r<\/sup> Aaron M. Drucker (FRCPC), dermatologue et chercheur, de nous parler de la phototh\u00e9rapie dans le traitement de l\u2019ecz\u00e9ma.<\/p>\n<p><strong>La a phototh\u00e9rapie contre l&rsquo;eczema<\/strong><\/p>\n<p>L\u2019ecz\u00e9ma, y compris la dermatite atopique, est g\u00e9n\u00e9ralement trait\u00e9 au moyen de m\u00e9dicaments topiques offerts sous forme de cr\u00e8mes ou d\u2019onguents. Il arrive toutefois que ces m\u00e9dicaments topiques ne parviennent pas \u00e0 att\u00e9nuer l\u2019ecz\u00e9ma; \u00e0 ce stade, le m\u00e9decin pourrait recommander la phototh\u00e9rapie pour aider \u00e0 ma\u00eetriser l\u2019affection.<\/p>\n<p><strong>Qu&rsquo;est-ce que la phototh\u00e9rapie? <\/strong><\/p>\n<p>La phototh\u00e9rapie repose sur l\u2019utilisation de la lumi\u00e8re ultraviolette pour traiter l\u2019ecz\u00e9ma qui n\u2019est pas ma\u00eetris\u00e9 par des traitements topiques. Elle peut \u00eatre recommand\u00e9e par un dermatologue et est g\u00e9n\u00e9ralement offerte en clinique de dermatologie. Les rayons ultraviolets (UV) utilis\u00e9s sont soit des UVA ou des UVB. Au Canada, les UVB sont les plus souvent utilis\u00e9s. Le traitement peut viser tout le corps en m\u00eame temps, ou encore cibler les mains ou les pieds \u00e0 l\u2019aide d\u2019appareils sp\u00e9cialis\u00e9s.<\/p>\n<p><strong>Comment fonctionne la phototh\u00e9rapie?<\/strong><\/p>\n<p>Les rayons naturels du soleil aident \u00e0 r\u00e9duire les sympt\u00f4mes chez certaines personnes atteintes d\u2019ecz\u00e9ma en diminuant la r\u00e9ponse inflammatoire de la peau, alors que chez d\u2019autres, le soleil peut provoquer une pouss\u00e9e d\u2019ecz\u00e9ma! La phototh\u00e9rapie permet de contr\u00f4ler tr\u00e8s \u00e9troitement la longueur d\u2019onde (le type de rayonnement UV) et d\u2019administrer une \u00ab\u00a0dose\u00a0\u00bb de lumi\u00e8re qui peut att\u00e9nuer les sympt\u00f4mes. L\u2019exposition initiale \u00e0 la phototh\u00e9rapie est tr\u00e8s courte, par exemple de quelques secondes seulement, et augmente au fil du temps. Un cycle de traitement type pourrait \u00eatre de deux ou trois expositions par semaine, pendant dix ou douze semaines. On peut constater une am\u00e9lioration imm\u00e9diate chez certains patients, alors que chez d\u2019autres, cela peut prendre plusieurs semaines. Chez certains patients, la phototh\u00e9rapie n\u2019est pas efficace et peut m\u00eame aggraver les sympt\u00f4mes.<\/p>\n<p><strong>\u00c0 quoi peut-on s&rsquo;attendre lors d&rsquo;une s\u00e9ance de phototh\u00e9rapie?<\/strong><\/p>\n<p>Une s\u00e9ance de phototh\u00e9rapie se d\u00e9roule dans une cabine priv\u00e9e dans une pi\u00e8ce pouvant \u00eatre verrouill\u00e9e de l&rsquo;int\u00e9rieur, ou \u00e0 l\u2019aide d\u2019appareils sp\u00e9cialis\u00e9s pour traiter les mains ou les pieds. La cabine ou l\u2019appareil sont dot\u00e9s d\u2019ampoules qui \u00e9mettent des rayons UV. Dans la cabine, le patient est compl\u00e8tement d\u00e9v\u00eatu, \u00e0 l\u2019exception de ses sous-v\u00eatements, et porte des lunettes pour se prot\u00e9ger les yeux. L\u2019exposition peut \u00eatre de quelques secondes seulement en d\u00e9but de traitement, et sa dur\u00e9e peut augmenter au fil du temps.<\/p>\n<p><strong>Quels sont les effets secondaires possibles de la phototh\u00e9rapie?<\/strong><\/p>\n<p>Votre dermatologue et votre infirmier ou infirmi\u00e8re planifieront les expositions de fa\u00e7on \u00e0 r\u00e9duire le plus possible les effets secondaires et \u00e0 \u00e9viter les br\u00fblures de la peau. Les effets secondaires courants comprennent la sensation de chaleur pendant le traitement et une rougeur de la peau apr\u00e8s celui-ci. Il est important de signaler \u00e0 la clinique de phototh\u00e9rapie tout \u00ab\u00a0coup de soleil\u00a0\u00bb qui appara\u00eet apr\u00e8s un traitement. M\u00eame si les doses de rayons UV administr\u00e9es en phototh\u00e9rapie sont g\u00e9n\u00e9ralement faibles, ce traitement peut contribuer \u00e0 certains probl\u00e8mes comme le vieillissement pr\u00e9matur\u00e9 de la peau et accro\u00eetre le risque de cancer de la peau. Le risque associ\u00e9 \u00e0 la plupart des types de phototh\u00e9rapie est consid\u00e9r\u00e9 comme tr\u00e8s faible.<\/p>\n<p><strong>Dois-je continuer mes traitments topiques et l&rsquo;application de mes hydrants pendant la phototh\u00e9rapie?<\/strong><\/p>\n<p>Vous devez suivre les directives de votre dermatologue concernant l\u2019utilisation des traitements topiques et des hydratants pendant la phototh\u00e9rapie. En g\u00e9n\u00e9ral, les patients continuent d\u2019appliquer leurs traitements topiques et leurs hydratants pendant un cycle de phototh\u00e9rapie; il pourrait toutefois \u00eatre pr\u00e9f\u00e9rable d\u2019\u00e9viter de les appliquer imm\u00e9diatement avant un traitement. Certaines cliniques recommandent de ne rien appliquer sur la peau au moins une heure avant le d\u00e9but de la s\u00e9ance de traitement. Votre m\u00e9decin ou infirmier\/infirmi\u00e8re vous donnera des directives pr\u00e9cises \u00e0 ce sujet.<\/p>\n<p><strong>La phototh\u00e9rapie se compare-t-elle aux salons de bronzage ou aux bains de soleil \u00e0 la page?\u00a0<\/strong><\/p>\n<p>Les lits de bronzage, et m\u00eame les rayons naturels du soleil, ne sont pas \u00e9quivalents \u00e0 la phototh\u00e9rapie offerte dans un h\u00f4pital ou une clinique. Les lits de bronzage \u00e9mettent des rayons UV \u00e0 large spectre et ne sont pas encadr\u00e9s par des professionnels de la sant\u00e9 \u2013 il est impossible de d\u00e9terminer la quantit\u00e9 de lumi\u00e8re ou la longueur d\u2019onde re\u00e7ue. Contrairement \u00e0 la phototh\u00e9rapie par UVB, les lits de bronzage augmentent consid\u00e9rablement le risque de cancer de la peau, et il est d\u00e9conseill\u00e9 d\u2019y avoir recours pour traiter les probl\u00e8mes de peau ou pour bronzer. Profitez de la lumi\u00e8re naturelle du soleil tout en vous prot\u00e9geant, par exemple en r\u00e9duisant votre exposition au soleil au milieu de la journ\u00e9e (de 10\u00a0h \u00e0 16\u00a0h), en portant des v\u00eatements et des lunettes pour vous prot\u00e9ger la peau et les yeux et en appliquant un \u00e9cran solaire. Les rayons naturels du soleil ne peuvent pas remplacer la phototh\u00e9rapie.<\/p>\n<p>La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma remercie le D<sup>r<\/sup> Aaron M. Drucker (FRCPC) de sa contribution volontaire \u00e0 cette ressource \u00e9ducative.<\/p>\n<p><em>Avis de non-responsabilit\u00e9\u00a0: L\u2019information contenue dans cette ressource ne remplace pas les conseils d\u2019un m\u00e9decin et ne doit pas servir d\u2019outil diagnostique.\u00a0L\u2019information \u00e9tait \u00e0 jour \u00e0 la date de publication. Les interventions, les m\u00e9dicaments et les plans de traitement sont tous associ\u00e9s \u00e0 des risques et \u00e0 des bienfaits. Il est donc important de discuter de ses besoins particuliers ou de ceux de son enfant avec un professionnel de la sant\u00e9 qualifi\u00e9.\u00a0<\/em><\/p>\n<p>Ao\u00fbt 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phototh\u00e9rapie contre l\u2019ecz\u00e9ma : comment \u00e7a consiste? Qu\u2019est-ce que la phototh\u00e9rapie, et comment peut-elle aider les personnes atteintes d\u2019ecz\u00e9ma? Est-ce un peu comme de passer du temps au soleil?\u00a0La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma a demand\u00e9 au Dr Aaron M. Drucker (FRCPC), dermatologue et chercheur, de nous parler de la phototh\u00e9rapie dans le traitement de l\u2019ecz\u00e9ma. [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":2594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-3829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-un-medecin-vous-parle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada\" \/>\n<meta property=\"og:description\" content=\"Phototh\u00e9rapie contre l\u2019ecz\u00e9ma : comment \u00e7a consiste? Qu\u2019est-ce que la phototh\u00e9rapie, et comment peut-elle aider les personnes atteintes d\u2019ecz\u00e9ma? Est-ce un peu comme de passer du temps au soleil?\u00a0La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma a demand\u00e9 au Dr Aaron M. Drucker (FRCPC), dermatologue et chercheur, de nous parler de la phototh\u00e9rapie dans le traitement de l\u2019ecz\u00e9ma. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/\" \/>\n<meta property=\"og:site_name\" content=\"Eczema Society of Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EczemaSocietyofCanada\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-31T19:13:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T21:23:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1127\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AministratorESC_m6345kegtcv93\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:site\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AministratorESC_m6345kegtcv93\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/\"},\"author\":{\"name\":\"AministratorESC_m6345kegtcv93\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\"},\"headline\":\"Un m\u00e9decin vous parle&#8230; de phototh\u00e9rapie\",\"datePublished\":\"2022-01-31T19:13:48+00:00\",\"dateModified\":\"2024-12-19T21:23:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/\"},\"wordCount\":1065,\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pexels-photo-3946168.jpeg\",\"articleSection\":[\"Un m\u00e9decin vous parle\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/\",\"name\":\"Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pexels-photo-3946168.jpeg\",\"datePublished\":\"2022-01-31T19:13:48+00:00\",\"dateModified\":\"2024-12-19T21:23:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pexels-photo-3946168.jpeg\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/pexels-photo-3946168.jpeg\",\"width\":1127,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/un-medecin-vous-parle-de-phototherapie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un m\u00e9decin vous parle&#8230; de phototh\u00e9rapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"name\":\"Eczema Society of Canada\",\"description\":\"Educational Resources\",\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\",\"name\":\"Eczema Society of Canada\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"width\":362,\"height\":360,\"caption\":\"Eczema Society of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EczemaSocietyofCanada\",\"https:\\\/\\\/x.com\\\/EczemaSocietyCA\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EczemaHelp\",\"https:\\\/\\\/www.instagram.com\\\/eczemasocietyofcanada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\",\"name\":\"AministratorESC_m6345kegtcv93\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"caption\":\"AministratorESC_m6345kegtcv93\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/","og_locale":"fr_FR","og_type":"article","og_title":"Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada","og_description":"Phototh\u00e9rapie contre l\u2019ecz\u00e9ma : comment \u00e7a consiste? Qu\u2019est-ce que la phototh\u00e9rapie, et comment peut-elle aider les personnes atteintes d\u2019ecz\u00e9ma? Est-ce un peu comme de passer du temps au soleil?\u00a0La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma a demand\u00e9 au Dr Aaron M. Drucker (FRCPC), dermatologue et chercheur, de nous parler de la phototh\u00e9rapie dans le traitement de l\u2019ecz\u00e9ma. [&hellip;]","og_url":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/","og_site_name":"Eczema Society of Canada","article_publisher":"https:\/\/www.facebook.com\/EczemaSocietyofCanada","article_published_time":"2022-01-31T19:13:48+00:00","article_modified_time":"2024-12-19T21:23:30+00:00","og_image":[{"width":1127,"height":750,"url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg","type":"image\/jpeg"}],"author":"AministratorESC_m6345kegtcv93","twitter_card":"summary_large_image","twitter_creator":"@EczemaSocietyCA","twitter_site":"@EczemaSocietyCA","twitter_misc":{"\u00c9crit par":"AministratorESC_m6345kegtcv93","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#article","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/"},"author":{"name":"AministratorESC_m6345kegtcv93","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24"},"headline":"Un m\u00e9decin vous parle&#8230; de phototh\u00e9rapie","datePublished":"2022-01-31T19:13:48+00:00","dateModified":"2024-12-19T21:23:30+00:00","mainEntityOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/"},"wordCount":1065,"publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg","articleSection":["Un m\u00e9decin vous parle"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/","url":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/","name":"Un m\u00e9decin vous parle... de phototh\u00e9rapie | Eczema Society of Canada","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#primaryimage"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg","datePublished":"2022-01-31T19:13:48+00:00","dateModified":"2024-12-19T21:23:30+00:00","breadcrumb":{"@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#primaryimage","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2021\/12\/pexels-photo-3946168.jpeg","width":1127,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/eczemahelp.ca\/fr\/un-medecin-vous-parle-de-phototherapie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eczemahelp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Un m\u00e9decin vous parle&#8230; de phototh\u00e9rapie"}]},{"@type":"WebSite","@id":"https:\/\/eczemahelp.ca\/fr\/#website","url":"https:\/\/eczemahelp.ca\/fr\/","name":"Eczema Society of Canada","description":"Educational Resources","publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eczemahelp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eczemahelp.ca\/fr\/#organization","name":"Eczema Society of Canada","url":"https:\/\/eczemahelp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","width":362,"height":360,"caption":"Eczema Society of Canada"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EczemaSocietyofCanada","https:\/\/x.com\/EczemaSocietyCA","https:\/\/www.youtube.com\/user\/EczemaHelp","https:\/\/www.instagram.com\/eczemasocietyofcanada\/"]},{"@type":"Person","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24","name":"AministratorESC_m6345kegtcv93","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","url":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","caption":"AministratorESC_m6345kegtcv93"}}]}},"_links":{"self":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/comments?post=3829"}],"version-history":[{"count":0,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media\/2594"}],"wp:attachment":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media?parent=3829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/categories?post=3829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/tags?post=3829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}