{"id":3850,"date":"2022-08-09T14:20:11","date_gmt":"2022-08-09T14:20:11","guid":{"rendered":"https:\/\/eczemahelp.ca\/blog\/racontez-votre-histoire-lhistoire-de-tanya\/"},"modified":"2024-11-04T16:27:52","modified_gmt":"2024-11-04T16:27:52","slug":"racontez-votre-histoire-lhistoire-de-tanya","status":"publish","type":"post","link":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/","title":{"rendered":"Racontez votre histoire : l&rsquo;histoire de Tanya"},"content":{"rendered":"<h1>L\u2019histoire de Tanya avec l\u2019ecz\u00e9ma<\/h1>\n<p><strong>Parvenir \u00e0 l&rsquo;acceptation, en tant qu\u2019aidante et de personne atteinte d\u2019ecz\u00e9ma<\/strong><\/p>\n<p><img fetchpriority=\"high\" class=\"alignright wp-image-4992 size-full\" title=\"Racontez votre histoire : l'histoire de Tanya\" src=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-1-240x300-1.jpg\" alt=\"Racontez votre histoire : l'histoire de Tanya\" width=\"240\" height=\"300\" \/>Souffrir d\u2019ecz\u00e9ma mod\u00e9r\u00e9 ou s\u00e9v\u00e8re peut vous faire sentir comme un expert en la mati\u00e8re. Quand une personne atteinte d\u2019ecz\u00e9ma devient le parent d\u2019un enfant ecz\u00e9mateux, comment les connaissances acquises la soutiennent-elles dans son nouveau r\u00f4le d&rsquo;aidant?<\/p>\n<p>Nous avons invit\u00e9 Tanya Mohan, b\u00e9n\u00e9vole et ambassadrice pour la SCE, et elle-m\u00eame atteinte d\u2019ecz\u00e9ma, \u00e0 parler de l\u2019exp\u00e9rience v\u00e9cue par sa famille et de ce qu\u2019elle a appris au fil du temps.<\/p>\n<p>\u00ab\u00a0\u00c0 la naissance de mon fils, j\u2019ai pens\u00e9 qu\u2019il y avait de tr\u00e8s fortes chances qu\u2019il souffre d\u2019ecz\u00e9ma. Apr\u00e8s quelques jours seulement, l\u2019ecz\u00e9ma est apparu, et j&rsquo;ai su qu\u2019il serait semblable au mien. Je n\u2019ai pas trop mal r\u00e9agi au d\u00e9part \u2013 c\u2019est comme si je m\u2019y attendais, et j&rsquo;avais bon espoir de savoir comment le ma\u00eetriser. De plus, je n&rsquo;avais pas de craintes par rapport aux corticost\u00e9ro\u00efdes qui lui seraient, j&rsquo;en \u00e9tais certaine, prescrits.<\/p>\n<p>Plus le temps passait, et plus je constatais les d\u00e9sagr\u00e9ments que lui causaient les d\u00e9mangeaisons. Cela m\u2019a fait revivre TANT de sentiments douloureux que j&rsquo;avais moi-m\u00eame \u00e9prouv\u00e9s, que \u00e7a a \u00e9t\u00e9, et continue d\u2019\u00eatre difficile de ne pas attribuer ces sentiments \u00e0 mon fils.<\/p>\n<p>Le fait d\u2019\u00eatre une aidante atteinte d\u2019ecz\u00e9ma mod\u00e9r\u00e9 ou s\u00e9v\u00e8re et de prendre soin d\u2019un b\u00e9b\u00e9 lui aussi atteint de ces formes d\u2019ecz\u00e9ma est tout un d\u00e9fi. Je comprends bien l&rsquo;affection et je crois qu\u2019en g\u00e9n\u00e9ral, je sais quoi faire pour soulager les d\u00e9mangeaisons, quelle cr\u00e8me utiliser et \u00e0 quelle temp\u00e9rature garder la maison, mais je crains de tenir pour acquis, \u00e0 tort, que sa peau est identique \u00e0 la mienne.<\/p>\n<p>Je trouve qu\u2019il est aidant de faire comme si j\u2019\u00e9tais nouvelle dans le monde de l&rsquo;ecz\u00e9ma quand vient le temps de le traiter ou d&rsquo;aller \u00e0 ses rendez-vous. Je prends cette approche, car le traitement de l\u2019ecz\u00e9ma d\u2019un enfant peut diff\u00e9rer de celui d\u2019un adulte, et les traitements de l&rsquo;ecz\u00e9ma ont \u00e9norm\u00e9ment \u00e9volu\u00e9 depuis mon enfance.<\/p>\n<p>Le fait de g\u00e9rer sa propre sant\u00e9 est tr\u00e8s important \u00e0 mes yeux, tant en tant que patiente que de m\u00e8re. Cela m\u2019a aid\u00e9 \u00e0 accepter la maladie pour ce qu\u2019elle est : quelque chose de chronique qui ne partira pas. Il faut la traiter ainsi, et m\u00eame si c&rsquo;est \u00e9reintant, cette acceptation m\u2019aide \u00e0 composer avec les hauts et les bas qui accompagnent ce parcours.<\/p>\n<p>Les membres de ma famille ont aussi appris qu\u2019il est essentiel de partager la responsabilit\u00e9 des soins de la peau. Il vaut mieux \u00e9viter de faire d\u2019une seule personne l&rsquo;unique experte en mati\u00e8re d\u2019hydratation, de bains et d&rsquo;application des traitements pour permettre de changer les r\u00f4les et d&rsquo;avoir des moments de r\u00e9pit.<\/p>\n<p>Dans l\u2019ensemble, mon exp\u00e9rience m&rsquo;a permis de me sentir moins d\u00e9pass\u00e9e par l&rsquo;affection de mon fils. J&rsquo;ai accept\u00e9 qu&rsquo;elle soit chronique et qu\u2019elle risque d\u2019\u00eatre l\u00e0 pour le reste de sa vie. Pour les parents qui voient le d\u00e9fi comme \u00e9tant insurmontable, sachez qu\u2019il est possible de soutenir votre enfant, de composer avec les pouss\u00e9es et de l\u2019aider \u00e0 vivre sa vie malgr\u00e9 l\u2019ecz\u00e9ma.\u00a0\u00bb<\/p>\n<p><em>Au nom de la SCE, nous remercions chaque personne qui raconte son histoire afin de renforcer la collectivit\u00e9, d\u2019offrir du soutien et de faire en sorte que d\u2019autres personnes se sentent plus \u00e0 l\u2019aise et mieux dans leur peau. Vous d\u00e9sirez raconter votre histoire? \u00c9crivez-nous \u00e0\u00a0<\/em><a href=\"mailto:info@eczemahelp.ca\"><em>info@eczemahelp.ca<\/em><\/a><em>\u00a0sans tarder.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019histoire de Tanya avec l\u2019ecz\u00e9ma Parvenir \u00e0 l&rsquo;acceptation, en tant qu\u2019aidante et de personne atteinte d\u2019ecz\u00e9ma Souffrir d\u2019ecz\u00e9ma mod\u00e9r\u00e9 ou s\u00e9v\u00e8re peut vous faire sentir comme un expert en la mati\u00e8re. Quand une personne atteinte d\u2019ecz\u00e9ma devient le parent d\u2019un enfant ecz\u00e9mateux, comment les connaissances acquises la soutiennent-elles dans son nouveau r\u00f4le d&rsquo;aidant? Nous avons [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":2677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-3850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-avec-leczema"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Racontez votre histoire : l&#039;histoire de Tanya | Eczema Society of Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Racontez votre histoire : l&#039;histoire de Tanya | Eczema Society of Canada\" \/>\n<meta property=\"og:description\" content=\"L\u2019histoire de Tanya avec l\u2019ecz\u00e9ma Parvenir \u00e0 l&rsquo;acceptation, en tant qu\u2019aidante et de personne atteinte d\u2019ecz\u00e9ma Souffrir d\u2019ecz\u00e9ma mod\u00e9r\u00e9 ou s\u00e9v\u00e8re peut vous faire sentir comme un expert en la mati\u00e8re. Quand une personne atteinte d\u2019ecz\u00e9ma devient le parent d\u2019un enfant ecz\u00e9mateux, comment les connaissances acquises la soutiennent-elles dans son nouveau r\u00f4le d&rsquo;aidant? Nous avons [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/\" \/>\n<meta property=\"og:site_name\" content=\"Eczema Society of Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EczemaSocietyofCanada\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-09T14:20:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-04T16:27:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AministratorESC_m6345kegtcv93\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:site\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AministratorESC_m6345kegtcv93\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/\"},\"author\":{\"name\":\"AministratorESC_m6345kegtcv93\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\"},\"headline\":\"Racontez votre histoire : l&rsquo;histoire de Tanya\",\"datePublished\":\"2022-08-09T14:20:11+00:00\",\"dateModified\":\"2024-11-04T16:27:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/\"},\"wordCount\":682,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg\",\"articleSection\":[\"Vivre avec l\u2019ecz\u00e9ma\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/\",\"name\":\"Racontez votre histoire : l'histoire de Tanya | Eczema Society of Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg\",\"datePublished\":\"2022-08-09T14:20:11+00:00\",\"dateModified\":\"2024-11-04T16:27:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg\",\"width\":2048,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/racontez-votre-histoire-lhistoire-de-tanya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Racontez votre histoire : l&#8217;histoire de Tanya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"name\":\"Eczema Society of Canada\",\"description\":\"Educational Resources\",\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\",\"name\":\"Eczema Society of Canada\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"width\":362,\"height\":360,\"caption\":\"Eczema Society of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EczemaSocietyofCanada\",\"https:\\\/\\\/x.com\\\/EczemaSocietyCA\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EczemaHelp\",\"https:\\\/\\\/www.instagram.com\\\/eczemasocietyofcanada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\",\"name\":\"AministratorESC_m6345kegtcv93\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"caption\":\"AministratorESC_m6345kegtcv93\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Racontez votre histoire : l'histoire de Tanya | Eczema Society of Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/","og_locale":"fr_FR","og_type":"article","og_title":"Racontez votre histoire : l'histoire de Tanya | Eczema Society of Canada","og_description":"L\u2019histoire de Tanya avec l\u2019ecz\u00e9ma Parvenir \u00e0 l&rsquo;acceptation, en tant qu\u2019aidante et de personne atteinte d\u2019ecz\u00e9ma Souffrir d\u2019ecz\u00e9ma mod\u00e9r\u00e9 ou s\u00e9v\u00e8re peut vous faire sentir comme un expert en la mati\u00e8re. Quand une personne atteinte d\u2019ecz\u00e9ma devient le parent d\u2019un enfant ecz\u00e9mateux, comment les connaissances acquises la soutiennent-elles dans son nouveau r\u00f4le d&rsquo;aidant? Nous avons [&hellip;]","og_url":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/","og_site_name":"Eczema Society of Canada","article_publisher":"https:\/\/www.facebook.com\/EczemaSocietyofCanada","article_published_time":"2022-08-09T14:20:11+00:00","article_modified_time":"2024-11-04T16:27:52+00:00","og_image":[{"width":2048,"height":2560,"url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg","type":"image\/jpeg"}],"author":"AministratorESC_m6345kegtcv93","twitter_card":"summary_large_image","twitter_creator":"@EczemaSocietyCA","twitter_site":"@EczemaSocietyCA","twitter_misc":{"\u00c9crit par":"AministratorESC_m6345kegtcv93","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#article","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/"},"author":{"name":"AministratorESC_m6345kegtcv93","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24"},"headline":"Racontez votre histoire : l&rsquo;histoire de Tanya","datePublished":"2022-08-09T14:20:11+00:00","dateModified":"2024-11-04T16:27:52+00:00","mainEntityOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/"},"wordCount":682,"commentCount":0,"publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg","articleSection":["Vivre avec l\u2019ecz\u00e9ma"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/","url":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/","name":"Racontez votre histoire : l'histoire de Tanya | Eczema Society of Canada","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#primaryimage"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg","datePublished":"2022-08-09T14:20:11+00:00","dateModified":"2024-11-04T16:27:52+00:00","breadcrumb":{"@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#primaryimage","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/06\/tembinkosi-sikupela-opqGuOr1bHM-unsplash-scaled-1.jpg","width":2048,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/eczemahelp.ca\/fr\/racontez-votre-histoire-lhistoire-de-tanya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eczemahelp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Racontez votre histoire : l&#8217;histoire de Tanya"}]},{"@type":"WebSite","@id":"https:\/\/eczemahelp.ca\/fr\/#website","url":"https:\/\/eczemahelp.ca\/fr\/","name":"Eczema Society of Canada","description":"Educational Resources","publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eczemahelp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eczemahelp.ca\/fr\/#organization","name":"Eczema Society of Canada","url":"https:\/\/eczemahelp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","width":362,"height":360,"caption":"Eczema Society of Canada"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EczemaSocietyofCanada","https:\/\/x.com\/EczemaSocietyCA","https:\/\/www.youtube.com\/user\/EczemaHelp","https:\/\/www.instagram.com\/eczemasocietyofcanada\/"]},{"@type":"Person","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24","name":"AministratorESC_m6345kegtcv93","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","url":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","caption":"AministratorESC_m6345kegtcv93"}}]}},"_links":{"self":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/comments?post=3850"}],"version-history":[{"count":0,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media\/2677"}],"wp:attachment":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media?parent=3850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/categories?post=3850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/tags?post=3850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}