{"id":3866,"date":"2022-08-24T18:21:21","date_gmt":"2022-08-24T18:21:21","guid":{"rendered":"https:\/\/eczemahelp.ca\/blog\/quest-ce-que-la-dermatite-de-contact-et-comment-differe-t-elle-des-autres-formes-deczema\/"},"modified":"2024-12-19T20:40:16","modified_gmt":"2024-12-19T20:40:16","slug":"quest-ce-que-la-dermatite-de-contact-et-comment-differe-t-elle-des-autres-formes-deczema","status":"publish","type":"post","link":"https:\/\/eczemahelp.ca\/fr\/quest-ce-que-la-dermatite-de-contact-et-comment-differe-t-elle-des-autres-formes-deczema\/","title":{"rendered":"Qu&rsquo;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma?"},"content":{"rendered":"<h1>La dermatite de contact et les autres formes d\u2019ecz\u00e9ma<\/h1>\n<p>\u00ab Ecz\u00e9ma \u00bb est un terme g\u00e9n\u00e9rique servant \u00e0 d\u00e9crire plusieurs affections, y compris la dermatite atopique, la dermatite de contact, l\u2019ecz\u00e9ma chronique des mains et l\u2019ecz\u00e9ma s\u00e9borrh\u00e9ique, entre autres.<\/p>\n<p><img fetchpriority=\"high\" class=\"alignright wp-image-5263 size-medium\" title=\"Qu'est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes\" src=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1-1-300x200.jpg 300w, https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1-1-1024x682.jpg 1024w, https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1-1-768x512.jpg 768w, https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1-1.jpg 1400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>La SCE a r\u00e9cemment demand\u00e9 \u00e0 la D<sup>re<\/sup> Marissa Joseph, p\u00e9diatre-dermatologue (FRCPC), de nous expliquer la diff\u00e9rence entre la dermatite de contact et les autres formes d\u2019ecz\u00e9ma. Voici ce qu\u2019elle avait \u00e0 dire :<\/p>\n<p>\u00ab La dermatite de contact est un type d&rsquo;ecz\u00e9ma qui survient \u00e0 la suite d\u2019une irritation de la peau, apr\u00e8s un contact avec une substance irritante. Il y a deux formes de dermatite de contact : de contact irritant ou de contact allergique. Les deux formes sont diff\u00e9rentes et requi\u00e8rent un traitement distinct.<\/p>\n<p>La dermatite de contact irritant est en cause dans environ 80 pour cent des cas de dermatite de contact et survient quand les cellules cutan\u00e9es sont endommag\u00e9es apr\u00e8s un contact avec une substance irritante, comme de la laine qui pique ou une grande quantit\u00e9 de d\u00e9sinfectant pour les mains.<\/p>\n<p>La dermatite de contact allergique est une r\u00e9ponse immunitaire survenant dans une r\u00e9gion de la peau qui a \u00e9t\u00e9 expos\u00e9e \u00e0 une substance ayant d\u00e9clench\u00e9 une r\u00e9action allergique. \u00bb<\/p>\n<p>Bien que la DA et la dermatite de contact soient des types distincts d\u2019ecz\u00e9ma, selon la D<sup>re<\/sup> Joseph, \u00ab les deux peuvent \u00eatre li\u00e9es, car une personne souffrant de dermatite atopique \u2013 soit une peau g\u00e9n\u00e9tiquement sensible \u2013 est plus susceptible d&rsquo;avoir aussi des allergies de contact \u00e0 diff\u00e9rentes substances. C&rsquo;est pourquoi ce que vous mettez sur votre peau est si important \u00bb.<\/p>\n<p>Si vous pr\u00e9sentez des sympt\u00f4mes laissant pr\u00e9sager une dermatite de contact, parlez \u00e0 votre m\u00e9decin pour savoir comment les soulager.<\/p>\n<p>La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma (SCE) remercie la D<sup>re<\/sup> Dre Marissa Joseph (FRCPC) d&rsquo;avoir fait part de son expertise au cours des s\u00e9ances virtuelles \u00ab\u00a0Vivre avec l\u2019ecz\u00e9ma\u00a0\u00bb du mois de mars 2022 et pour le pr\u00e9sent contenu. Le financement des s\u00e9ances virtuelles \u00ab\u00a0Vivre avec l\u2019ecz\u00e9ma\u00a0\u00bb 2022 tenues \u00e0 l\u2019hiver a \u00e9t\u00e9 g\u00e9n\u00e9reusement octroy\u00e9 par Pfizer Canada et Sanofi Genzyme, division de sanofi-aventis Canada Inc.<\/p>\n<p><em>Avis de non-responsabilit\u00e9\u00a0: L\u2019information contenue dans cette ressource ne remplace pas les conseils d\u2019un m\u00e9decin et ne doit pas servir d\u2019outil diagnostique. L\u2019information \u00e9tait \u00e0 jour \u00e0 la date de publication. Tous les m\u00e9dicaments et plans de traitement et toutes les interventions sont associ\u00e9s \u00e0 des risques et \u00e0 des bienfaits. Il est important de discuter de ses besoins particuliers ou de ceux de son enfant avec un professionnel de la sant\u00e9 qualifi\u00e9.<\/em><\/p>\n<p>Mars 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La dermatite de contact et les autres formes d\u2019ecz\u00e9ma \u00ab Ecz\u00e9ma \u00bb est un terme g\u00e9n\u00e9rique servant \u00e0 d\u00e9crire plusieurs affections, y compris la dermatite atopique, la dermatite de contact, l\u2019ecz\u00e9ma chronique des mains et l\u2019ecz\u00e9ma s\u00e9borrh\u00e9ique, entre autres. La SCE a r\u00e9cemment demand\u00e9 \u00e0 la Dre Marissa Joseph, p\u00e9diatre-dermatologue (FRCPC), de nous expliquer la [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":2351,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-3866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-avec-leczema"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu&#039;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu&#039;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada\" \/>\n<meta property=\"og:description\" content=\"La dermatite de contact et les autres formes d\u2019ecz\u00e9ma \u00ab Ecz\u00e9ma \u00bb est un terme g\u00e9n\u00e9rique servant \u00e0 d\u00e9crire plusieurs affections, y compris la dermatite atopique, la dermatite de contact, l\u2019ecz\u00e9ma chronique des mains et l\u2019ecz\u00e9ma s\u00e9borrh\u00e9ique, entre autres. La SCE a r\u00e9cemment demand\u00e9 \u00e0 la Dre Marissa Joseph, p\u00e9diatre-dermatologue (FRCPC), de nous expliquer la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/\" \/>\n<meta property=\"og:site_name\" content=\"Eczema Society of Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EczemaSocietyofCanada\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T18:21:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T20:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AministratorESC_m6345kegtcv93\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:site\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AministratorESC_m6345kegtcv93\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/\"},\"author\":{\"name\":\"AministratorESC_m6345kegtcv93\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\"},\"headline\":\"Qu&rsquo;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma?\",\"datePublished\":\"2022-08-24T18:21:21+00:00\",\"dateModified\":\"2024-12-19T20:40:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/\"},\"wordCount\":483,\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-anna-shvets-3986970-1400x933-1.jpg\",\"articleSection\":[\"Vivre avec l\u2019ecz\u00e9ma\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/\",\"name\":\"Qu'est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-anna-shvets-3986970-1400x933-1.jpg\",\"datePublished\":\"2022-08-24T18:21:21+00:00\",\"dateModified\":\"2024-12-19T20:40:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-anna-shvets-3986970-1400x933-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-anna-shvets-3986970-1400x933-1.jpg\",\"width\":1400,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu&#8217;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#website\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/\",\"name\":\"Eczema Society of Canada\",\"description\":\"Educational Resources\",\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eczemahelp.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#organization\",\"name\":\"Eczema Society of Canada\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"width\":362,\"height\":360,\"caption\":\"Eczema Society of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EczemaSocietyofCanada\",\"https:\\\/\\\/x.com\\\/EczemaSocietyCA\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EczemaHelp\",\"https:\\\/\\\/www.instagram.com\\\/eczemasocietyofcanada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\",\"name\":\"AministratorESC_m6345kegtcv93\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234\",\"caption\":\"AministratorESC_m6345kegtcv93\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu'est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/","og_locale":"fr_FR","og_type":"article","og_title":"Qu'est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada","og_description":"La dermatite de contact et les autres formes d\u2019ecz\u00e9ma \u00ab Ecz\u00e9ma \u00bb est un terme g\u00e9n\u00e9rique servant \u00e0 d\u00e9crire plusieurs affections, y compris la dermatite atopique, la dermatite de contact, l\u2019ecz\u00e9ma chronique des mains et l\u2019ecz\u00e9ma s\u00e9borrh\u00e9ique, entre autres. La SCE a r\u00e9cemment demand\u00e9 \u00e0 la Dre Marissa Joseph, p\u00e9diatre-dermatologue (FRCPC), de nous expliquer la [&hellip;]","og_url":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/","og_site_name":"Eczema Society of Canada","article_publisher":"https:\/\/www.facebook.com\/EczemaSocietyofCanada","article_published_time":"2022-08-24T18:21:21+00:00","article_modified_time":"2024-12-19T20:40:16+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg","type":"image\/jpeg"}],"author":"AministratorESC_m6345kegtcv93","twitter_card":"summary_large_image","twitter_creator":"@EczemaSocietyCA","twitter_site":"@EczemaSocietyCA","twitter_misc":{"\u00c9crit par":"AministratorESC_m6345kegtcv93","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#article","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/"},"author":{"name":"AministratorESC_m6345kegtcv93","@id":"https:\/\/eczemahelp.ca\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24"},"headline":"Qu&rsquo;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma?","datePublished":"2022-08-24T18:21:21+00:00","dateModified":"2024-12-19T20:40:16+00:00","mainEntityOfPage":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/"},"wordCount":483,"publisher":{"@id":"https:\/\/eczemahelp.ca\/#organization"},"image":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg","articleSection":["Vivre avec l\u2019ecz\u00e9ma"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/","url":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/","name":"Qu'est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma? | Eczema Society of Canada","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#primaryimage"},"image":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg","datePublished":"2022-08-24T18:21:21+00:00","dateModified":"2024-12-19T20:40:16+00:00","breadcrumb":{"@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#primaryimage","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2022\/08\/pexels-anna-shvets-3986970-1400x933-1.jpg","width":1400,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/eczemahelp.ca\/what-is-contact-dermatitis-and-how-does-it-differ-from-other-forms-of-eczema\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eczemahelp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Qu&#8217;est-ce que la dermatite de contact, et comment diff\u00e8re-t-elle des autres formes d\u2019ecz\u00e9ma?"}]},{"@type":"WebSite","@id":"https:\/\/eczemahelp.ca\/#website","url":"https:\/\/eczemahelp.ca\/","name":"Eczema Society of Canada","description":"Educational Resources","publisher":{"@id":"https:\/\/eczemahelp.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eczemahelp.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eczemahelp.ca\/#organization","name":"Eczema Society of Canada","url":"https:\/\/eczemahelp.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/#\/schema\/logo\/image\/","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","width":362,"height":360,"caption":"Eczema Society of Canada"},"image":{"@id":"https:\/\/eczemahelp.ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EczemaSocietyofCanada","https:\/\/x.com\/EczemaSocietyCA","https:\/\/www.youtube.com\/user\/EczemaHelp","https:\/\/www.instagram.com\/eczemasocietyofcanada\/"]},{"@type":"Person","@id":"https:\/\/eczemahelp.ca\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24","name":"AministratorESC_m6345kegtcv93","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234","url":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1778619234","caption":"AministratorESC_m6345kegtcv93"}}]}},"_links":{"self":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/comments?post=3866"}],"version-history":[{"count":0,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/3866\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media\/2351"}],"wp:attachment":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media?parent=3866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/categories?post=3866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/tags?post=3866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}