{"id":8216,"date":"2023-11-22T19:39:09","date_gmt":"2023-11-22T19:39:09","guid":{"rendered":"https:\/\/eczemahelp.ca\/?p=8216"},"modified":"2024-12-19T21:25:42","modified_gmt":"2024-12-19T21:25:42","slug":"quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique","status":"publish","type":"post","link":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/","title":{"rendered":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?"},"content":{"rendered":"<h1>Quand passer \u00e0 un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?<\/h1>\r\n\r\n<p class=\"wp-block-paragraph\">La dermatite atopique (DA), la forme la plus commune d\u2019ecz\u00e9ma, se traite g\u00e9n\u00e9ralement par l\u2019hydratation de la peau, l\u2019\u00e9vitement des facteurs d\u00e9clencheurs et le recours \u00e0 des m\u00e9dicaments anti-inflammatoires topiques. Cette approche est pr\u00f4n\u00e9e dans les lignes directrices standard sur le traitement de la DA, partout dans le monde. Mais quelles sont les options offertes aux patients qui souffrent d\u2019ecz\u00e9ma s\u00e9v\u00e8re tr\u00e8s r\u00e9pandu qui ne r\u00e9pond pas aux traitements topiques?<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image alignright size-full\"><img fetchpriority=\"high\" width=\"382\" height=\"260\" class=\"wp-image-8217\" title=\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\" src=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\" alt=\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\" srcset=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg 382w, https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1-300x204.jpg 300w\" sizes=\"(max-width: 382px) 100vw, 382px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Quand un traitement \u00e0 action g\u00e9n\u00e9rale est-il appropri\u00e9?<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Dans une <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28803668\/\">publication de 2017<\/a> pr\u00e9sentant le point de vue de 29 experts mondiaux de renom sur la dermatite atopique, on souligne les recommandations formul\u00e9es par un groupe d&rsquo;experts form\u00e9 par le International Eczema Council. Le D<sup>r<\/sup> Aaron M. Drucker, dermatologue torontois, chercheur et m\u00e9decin-collaborateur b\u00e9n\u00e9vole de longue date pour la SCE, nous explique ce qui suit : \u00ab\u00a0Quand vient le temps de d\u00e9cider avec le patient s\u2019il convient de passer \u00e0 un traitement \u00e0 action g\u00e9n\u00e9rale apr\u00e8s l\u2019\u00e9chec des traitements topiques, le m\u00e9decin doit \u00e0 la fois \u00e9valuer la gravit\u00e9 de l&rsquo;ecz\u00e9ma, les sympt\u00f4mes du patient et sa qualit\u00e9 de vie \u00bb.\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Les traitements \u00e0 action g\u00e9n\u00e9rale de la DA s&rsquo;accompagnent de risques qui ne doivent pas \u00eatre pris \u00e0 la l\u00e9g\u00e8re. Le professionnel de la sant\u00e9, le patient et l&rsquo;aidant doivent d\u00e9terminer avec soin si les bienfaits potentiels l&#8217;emportent sur les risques associ\u00e9s au traitement.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le D<sup>r<\/sup> Drucker ajoute : \u00ab\u00a0Cet article a \u00e9t\u00e9 r\u00e9dig\u00e9 quand les options de traitement \u00e0 action g\u00e9n\u00e9rale \u00e9taient encore limit\u00e9es, avant l&rsquo;ajout des agents biologiques et des inhibiteurs de JAK dans le traitement de l\u2019ecz\u00e9ma. Les m\u00eames principes s&rsquo;appliquent toutefois, c&rsquo;est-\u00e0-dire qu\u2019il faut tenir compte des exp\u00e9riences et des valeurs des patients quand vient le temps de choisir une strat\u00e9gie th\u00e9rapeutique\u00a0\u00bb.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Les traitements \u00e0 action g\u00e9n\u00e9rale am\u00e9liorent la qualit\u00e9 de vie, mais la s\u00e9curit\u00e9 du patient doit primer sur le reste.<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Le D<sup>r<\/sup> Drucker insiste sur ce qui suit : \u00ab\u00a0Quand on monte d\u2019un cran et qu\u2019on passe des traitements topiques aux traitements \u00e0 action g\u00e9n\u00e9rale, on sait que les risques d&rsquo;effets ind\u00e9sirables seront aussi plus grands. C&rsquo;est une discussion importante qu\u2019il faut tenir avec les patients et les aidants.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Il ajoute : La plupart des personnes atteintes de DA arrivent \u00e0 traiter leur ecz\u00e9ma avec des hydratants et des traitements topiques sous ordonnance. La bonne nouvelle, c&rsquo;est que ceux qui continuent de souffrir ont maintenant des options \u00e0 leur disposition\u00a0\u00bb.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La Soci\u00e9t\u00e9 canadienne de l\u2019ecz\u00e9ma remercie le D<sup>r<\/sup> Aaron Drucker (FRCPC \u2013 dermatologie) de sa contribution volontaire \u00e0 ce contenu \u00e9ducatif.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">R\u00e9f\u00e9rence :<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Journal of the American Academy of Dermatology<\/em> (2017). When does atopic dermatitis warrant systemic therapy? Recommendations from an expert panel of the International Eczema Council. Oct;77(4): 623-633. <a href=\"https:\/\/www.jaad.org\/article\/S0190-9622(17)31944-8\/fulltext\">doi:<\/a><a href=\"https:\/\/www.jaad.org\/article\/S0190-9622(17)31944-8\/fulltext\"> 10.1016\/j.jaad.2017.06.042<\/a>.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Avis de non-responsabilit\u00e9\u00a0: L\u2019information contenue dans cette ressource ne remplace pas les conseils d\u2019un m\u00e9decin et ne doit pas servir d\u2019outil diagnostique. L\u2019information \u00e9tait \u00e0 jour \u00e0 la date de publication. Tous les m\u00e9dicaments et plans de traitement et toutes les interventions sont associ\u00e9s \u00e0 des risques et \u00e0 des bienfaits. Il est important de discuter de ses besoins particuliers ou de ceux de son enfant avec un professionnel de la sant\u00e9 qualifi\u00e9.<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Octobre 2023<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Quand passer \u00e0 un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique? La dermatite atopique (DA), la forme la plus commune d\u2019ecz\u00e9ma, se traite g\u00e9n\u00e9ralement par l\u2019hydratation de la peau, l\u2019\u00e9vitement des facteurs d\u00e9clencheurs et le recours \u00e0 des m\u00e9dicaments anti-inflammatoires topiques. Cette approche est pr\u00f4n\u00e9e dans les lignes directrices standard sur le traitement de [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":8217,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":["post-8216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivre-avec-leczema"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traiter la dermatite atopique<\/title>\n<meta name=\"description\" content=\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traiter la dermatite atopique\" \/>\n<meta property=\"og:description\" content=\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/\" \/>\n<meta property=\"og:site_name\" content=\"Eczema Society of Canada\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EczemaSocietyofCanada\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T19:39:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-19T21:25:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"382\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AministratorESC_m6345kegtcv93\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:site\" content=\"@EczemaSocietyCA\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"AministratorESC_m6345kegtcv93\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/\"},\"author\":{\"name\":\"AministratorESC_m6345kegtcv93\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\"},\"headline\":\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\",\"datePublished\":\"2023-11-22T19:39:09+00:00\",\"dateModified\":\"2024-12-19T21:25:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/\"},\"wordCount\":609,\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\",\"articleSection\":[\"Vivre avec l\u2019ecz\u00e9ma\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/\",\"name\":\"Traiter la dermatite atopique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\",\"datePublished\":\"2023-11-22T19:39:09+00:00\",\"dateModified\":\"2024-12-19T21:25:42+00:00\",\"description\":\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg\",\"width\":382,\"height\":260},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"name\":\"Eczema Society of Canada\",\"description\":\"Educational Resources\",\"publisher\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#organization\",\"name\":\"Eczema Society of Canada\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/logo.png\",\"width\":362,\"height\":360,\"caption\":\"Eczema Society of Canada\"},\"image\":{\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EczemaSocietyofCanada\",\"https:\\\/\\\/x.com\\\/EczemaSocietyCA\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/EczemaHelp\",\"https:\\\/\\\/www.instagram.com\\\/eczemasocietyofcanada\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/fr\\\/#\\\/schema\\\/person\\\/0b656986f78cbae0f1ce3df5ef2a6a24\",\"name\":\"AministratorESC_m6345kegtcv93\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"url\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"contentUrl\":\"https:\\\/\\\/eczemahelp.ca\\\/wp-content\\\/litespeed\\\/avatar\\\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616\",\"caption\":\"AministratorESC_m6345kegtcv93\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traiter la dermatite atopique","description":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/","og_locale":"fr_FR","og_type":"article","og_title":"Traiter la dermatite atopique","og_description":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?","og_url":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/","og_site_name":"Eczema Society of Canada","article_publisher":"https:\/\/www.facebook.com\/EczemaSocietyofCanada","article_published_time":"2023-11-22T19:39:09+00:00","article_modified_time":"2024-12-19T21:25:42+00:00","og_image":[{"width":382,"height":260,"url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg","type":"image\/jpeg"}],"author":"AministratorESC_m6345kegtcv93","twitter_card":"summary_large_image","twitter_creator":"@EczemaSocietyCA","twitter_site":"@EczemaSocietyCA","twitter_misc":{"\u00c9crit par":"AministratorESC_m6345kegtcv93","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#article","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/"},"author":{"name":"AministratorESC_m6345kegtcv93","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24"},"headline":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?","datePublished":"2023-11-22T19:39:09+00:00","dateModified":"2024-12-19T21:25:42+00:00","mainEntityOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/"},"wordCount":609,"publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg","articleSection":["Vivre avec l\u2019ecz\u00e9ma"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/","url":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/","name":"Traiter la dermatite atopique","isPartOf":{"@id":"https:\/\/eczemahelp.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#primaryimage"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#primaryimage"},"thumbnailUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg","datePublished":"2023-11-22T19:39:09+00:00","dateModified":"2024-12-19T21:25:42+00:00","description":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?","breadcrumb":{"@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#primaryimage","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/11\/1818-November-December-Social-Media_-systemic-treatments-blog-post_v1.jpg","width":382,"height":260},{"@type":"BreadcrumbList","@id":"https:\/\/eczemahelp.ca\/fr\/quand-les-specialistes-recommandent-ils-un-traitement-a-action-generale-contre-la-dermatite-atopique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eczemahelp.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Quand les sp\u00e9cialistes recommandent-ils un traitement \u00e0 action g\u00e9n\u00e9rale contre la dermatite atopique?"}]},{"@type":"WebSite","@id":"https:\/\/eczemahelp.ca\/fr\/#website","url":"https:\/\/eczemahelp.ca\/fr\/","name":"Eczema Society of Canada","description":"Educational Resources","publisher":{"@id":"https:\/\/eczemahelp.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eczemahelp.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eczemahelp.ca\/fr\/#organization","name":"Eczema Society of Canada","url":"https:\/\/eczemahelp.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/uploads\/2023\/06\/logo.png","width":362,"height":360,"caption":"Eczema Society of Canada"},"image":{"@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EczemaSocietyofCanada","https:\/\/x.com\/EczemaSocietyCA","https:\/\/www.youtube.com\/user\/EczemaHelp","https:\/\/www.instagram.com\/eczemasocietyofcanada\/"]},{"@type":"Person","@id":"https:\/\/eczemahelp.ca\/fr\/#\/schema\/person\/0b656986f78cbae0f1ce3df5ef2a6a24","name":"AministratorESC_m6345kegtcv93","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","url":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","contentUrl":"https:\/\/eczemahelp.ca\/wp-content\/litespeed\/avatar\/d59cdb18d6c9c6fecc51727424cc12fc.jpg?ver=1788298616","caption":"AministratorESC_m6345kegtcv93"}}]}},"_links":{"self":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/8216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/comments?post=8216"}],"version-history":[{"count":0,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/posts\/8216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media\/8217"}],"wp:attachment":[{"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/media?parent=8216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/categories?post=8216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eczemahelp.ca\/fr\/wp-json\/wp\/v2\/tags?post=8216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}